{"id":79134,"date":"2026-05-11T14:58:15","date_gmt":"2026-05-11T14:58:15","guid":{"rendered":"https:\/\/camping-latama.com\/glamping-unterkuenfte-2\/"},"modified":"2026-05-11T21:46:15","modified_gmt":"2026-05-11T21:46:15","slug":"glamping-unterkuenfte-2","status":"publish","type":"page","link":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/","title":{"rendered":"Eingerichtete Zelte"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":77062,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"avantage":[],"class_list":["post-79134","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ungew\u00f6hnliche Unterkunft Agde : Verbringen Sie eine ungew\u00f6hnliche Nacht in Cap d&#039;Agde<\/title>\n<meta name=\"description\" content=\"Buchen Sie Ihre ungew\u00f6hnliche Unterkunft in Cap d&#039;Agde und genie\u00dfen Sie einen originellen Aufenthalt zwischen Natur, Lagune und Komfort auf dem Campingplatz nur wenige Schritte vom Meer entfernt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ungew\u00f6hnliche Unterkunft Agde : Verbringen Sie eine ungew\u00f6hnliche Nacht in Cap d&#039;Agde\" \/>\n<meta property=\"og:description\" content=\"Buchen Sie Ihre ungew\u00f6hnliche Unterkunft in Cap d&#039;Agde und genie\u00dfen Sie einen originellen Aufenthalt zwischen Natur, Lagune und Komfort auf dem Campingplatz nur wenige Schritte vom Meer entfernt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Camping La Tama\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T21:46:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/camping-latama.com\/wp-content\/uploads\/2026\/03\/reservez-hebergement-insolite-cap-agde.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/\",\"url\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/\",\"name\":\"Ungew\u00f6hnliche Unterkunft Agde : Verbringen Sie eine ungew\u00f6hnliche Nacht in Cap d'Agde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/camping-latama.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/reservez-hebergement-insolite-cap-agde.jpg\",\"datePublished\":\"2026-05-11T14:58:15+00:00\",\"dateModified\":\"2026-05-11T21:46:15+00:00\",\"description\":\"Buchen Sie Ihre ungew\u00f6hnliche Unterkunft in Cap d'Agde und genie\u00dfen Sie einen originellen Aufenthalt zwischen Natur, Lagune und Komfort auf dem Campingplatz nur wenige Schritte vom Meer entfernt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/camping-latama.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/reservez-hebergement-insolite-cap-agde.jpg\",\"contentUrl\":\"https:\\\/\\\/camping-latama.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/reservez-hebergement-insolite-cap-agde.jpg\",\"width\":1920,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/glamping-unterkuenfte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Camping Cap d'Agde\",\"item\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ungew\u00f6hnliche Unterkunft Agde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/\",\"name\":\"Camping La Tamarissi\u00e8re\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/camping-latama.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ungew\u00f6hnliche Unterkunft Agde : Verbringen Sie eine ungew\u00f6hnliche Nacht in Cap d'Agde","description":"Buchen Sie Ihre ungew\u00f6hnliche Unterkunft in Cap d'Agde und genie\u00dfen Sie einen originellen Aufenthalt zwischen Natur, Lagune und Komfort auf dem Campingplatz nur wenige Schritte vom Meer entfernt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/","og_locale":"de_DE","og_type":"article","og_title":"Ungew\u00f6hnliche Unterkunft Agde : Verbringen Sie eine ungew\u00f6hnliche Nacht in Cap d'Agde","og_description":"Buchen Sie Ihre ungew\u00f6hnliche Unterkunft in Cap d'Agde und genie\u00dfen Sie einen originellen Aufenthalt zwischen Natur, Lagune und Komfort auf dem Campingplatz nur wenige Schritte vom Meer entfernt.","og_url":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/","og_site_name":"Camping La Tama","article_modified_time":"2026-05-11T21:46:15+00:00","og_image":[{"width":1920,"height":1000,"url":"https:\/\/camping-latama.com\/wp-content\/uploads\/2026\/03\/reservez-hebergement-insolite-cap-agde.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/","url":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/","name":"Ungew\u00f6hnliche Unterkunft Agde : Verbringen Sie eine ungew\u00f6hnliche Nacht in Cap d'Agde","isPartOf":{"@id":"https:\/\/camping-latama.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/#primaryimage"},"image":{"@id":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/#primaryimage"},"thumbnailUrl":"https:\/\/camping-latama.com\/wp-content\/uploads\/2026\/03\/reservez-hebergement-insolite-cap-agde.jpg","datePublished":"2026-05-11T14:58:15+00:00","dateModified":"2026-05-11T21:46:15+00:00","description":"Buchen Sie Ihre ungew\u00f6hnliche Unterkunft in Cap d'Agde und genie\u00dfen Sie einen originellen Aufenthalt zwischen Natur, Lagune und Komfort auf dem Campingplatz nur wenige Schritte vom Meer entfernt.","breadcrumb":{"@id":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/#primaryimage","url":"https:\/\/camping-latama.com\/wp-content\/uploads\/2026\/03\/reservez-hebergement-insolite-cap-agde.jpg","contentUrl":"https:\/\/camping-latama.com\/wp-content\/uploads\/2026\/03\/reservez-hebergement-insolite-cap-agde.jpg","width":1920,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/camping-latama.com\/de\/glamping-unterkuenfte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Camping Cap d'Agde","item":"https:\/\/camping-latama.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Ungew\u00f6hnliche Unterkunft Agde"}]},{"@type":"WebSite","@id":"https:\/\/camping-latama.com\/de\/#website","url":"https:\/\/camping-latama.com\/de\/","name":"Camping La Tamarissi\u00e8re","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/camping-latama.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/pages\/79134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/comments?post=79134"}],"version-history":[{"count":2,"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/pages\/79134\/revisions"}],"predecessor-version":[{"id":79151,"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/pages\/79134\/revisions\/79151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/media\/77062"}],"wp:attachment":[{"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/media?parent=79134"}],"wp:term":[{"taxonomy":"avantage","embeddable":true,"href":"https:\/\/camping-latama.com\/de\/wp-json\/wp\/v2\/avantage?post=79134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}